{"id":14132,"date":"2026-01-02T07:10:25","date_gmt":"2026-01-02T07:10:25","guid":{"rendered":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/"},"modified":"2026-03-27T09:00:12","modified_gmt":"2026-03-27T09:00:12","slug":"ursula-ulmer","status":"publish","type":"analyst","link":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/","title":{"rendered":"Ursula Ulmer"},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":18741,"template":"","iaap-status":[],"class_list":["post-14132","analyst","type-analyst","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ursula Ulmer - JungianDirectory<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ursula Ulmer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/\" \/>\n<meta property=\"og:site_name\" content=\"JungianDirectory\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T09:00:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/analystsprofilephotos\/Ulmer.Ursula.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/ursula-ulmer\\\/\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/ursula-ulmer\\\/\",\"name\":\"Ursula Ulmer - JungianDirectory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/ursula-ulmer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/ursula-ulmer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/analystsprofilephotos\\\/Ulmer.Ursula.jpg\",\"datePublished\":\"2026-01-02T07:10:25+00:00\",\"dateModified\":\"2026-03-27T09:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/ursula-ulmer\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/ursula-ulmer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/ursula-ulmer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/analystsprofilephotos\\\/Ulmer.Ursula.jpg\",\"contentUrl\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/analystsprofilephotos\\\/Ulmer.Ursula.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/ursula-ulmer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analysts\",\"item\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ursula Ulmer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#website\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\",\"name\":\"JungianDirectory\",\"description\":\"Analysts, Events, Training, CPD, Books, etc\",\"publisher\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#organization\",\"name\":\"JungianDirectory\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-new-logo-test-2024-03-03.png\",\"contentUrl\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-new-logo-test-2024-03-03.png\",\"width\":512,\"height\":512,\"caption\":\"JungianDirectory\"},\"image\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ursula Ulmer - JungianDirectory","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Ursula Ulmer","og_url":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/","og_site_name":"JungianDirectory","article_modified_time":"2026-03-27T09:00:12+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/analystsprofilephotos\/Ulmer.Ursula.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/","url":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/","name":"Ursula Ulmer - JungianDirectory","isPartOf":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/#primaryimage"},"image":{"@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/#primaryimage"},"thumbnailUrl":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/analystsprofilephotos\/Ulmer.Ursula.jpg","datePublished":"2026-01-02T07:10:25+00:00","dateModified":"2026-03-27T09:00:12+00:00","breadcrumb":{"@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/#primaryimage","url":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/analystsprofilephotos\/Ulmer.Ursula.jpg","contentUrl":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/analystsprofilephotos\/Ulmer.Ursula.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/ursula-ulmer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jungian.directory\/fcxfougk\/"},{"@type":"ListItem","position":2,"name":"Analysts","item":"https:\/\/jungian.directory\/fcxfougk\/analyst\/"},{"@type":"ListItem","position":3,"name":"Ursula Ulmer"}]},{"@type":"WebSite","@id":"https:\/\/jungian.directory\/fcxfougk\/#website","url":"https:\/\/jungian.directory\/fcxfougk\/","name":"JungianDirectory","description":"Analysts, Events, Training, CPD, Books, etc","publisher":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jungian.directory\/fcxfougk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/jungian.directory\/fcxfougk\/#organization","name":"JungianDirectory","url":"https:\/\/jungian.directory\/fcxfougk\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/jungian.directory\/fcxfougk\/#\/schema\/logo\/image\/","url":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2024\/02\/cropped-new-logo-test-2024-03-03.png","contentUrl":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2024\/02\/cropped-new-logo-test-2024-03-03.png","width":512,"height":512,"caption":"JungianDirectory"},"image":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst\/14132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst"}],"about":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/types\/analyst"}],"author":[{"embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst\/14132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/media\/18741"}],"wp:attachment":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/media?parent=14132"}],"wp:term":[{"taxonomy":"iaap-status","embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/iaap-status?post=14132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}