{"id":14914,"date":"2026-01-02T07:28:03","date_gmt":"2026-01-02T07:28:03","guid":{"rendered":"https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/"},"modified":"2026-01-03T20:33:13","modified_gmt":"2026-01-03T20:33:13","slug":"maria-grazia-di-giorgio","status":"publish","type":"analyst","link":"https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/","title":{"rendered":"Maria Grazia Di Giorgio"},"excerpt":{"rendered":"<p>Ms. Maria Grazia Di Giorgio is a Counselor &#8211; Mental Health based out of Boulder, Colorado and her medical specialization is Counselor &#8211; Mental Health. She practices in Boulder, Colorado and has the professional credentials of MA, LPC. The NPI Number for Ms. Maria Grazia Di Giorgio is 1922252402 and she holds a Licence No. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","iaap-status":[],"class_list":["post-14914","analyst","type-analyst","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Maria Grazia Di Giorgio - JungianDirectory<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maria Grazia Di Giorgio\" \/>\n<meta property=\"og:description\" content=\"Ms. Maria Grazia Di Giorgio is a Counselor &#8211; Mental Health based out of Boulder, Colorado and her medical specialization is Counselor &#8211; Mental Health. She practices in Boulder, Colorado and has the professional credentials of MA, LPC. The NPI Number for Ms. Maria Grazia Di Giorgio is 1922252402 and she holds a Licence No. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/\" \/>\n<meta property=\"og:site_name\" content=\"JungianDirectory\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-03T20:33:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/maria-grazia-di-giorgio\\\/\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/maria-grazia-di-giorgio\\\/\",\"name\":\"Maria Grazia Di Giorgio - JungianDirectory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#website\"},\"datePublished\":\"2026-01-02T07:28:03+00:00\",\"dateModified\":\"2026-01-03T20:33:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/maria-grazia-di-giorgio\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/maria-grazia-di-giorgio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/maria-grazia-di-giorgio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analysts\",\"item\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maria Grazia Di Giorgio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#website\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\",\"name\":\"JungianDirectory\",\"description\":\"Analysts, Events, Training, CPD, Books, etc\",\"publisher\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#organization\",\"name\":\"JungianDirectory\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-new-logo-test-2024-03-03.png\",\"contentUrl\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-new-logo-test-2024-03-03.png\",\"width\":512,\"height\":512,\"caption\":\"JungianDirectory\"},\"image\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maria Grazia Di Giorgio - JungianDirectory","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Maria Grazia Di Giorgio","og_description":"Ms. Maria Grazia Di Giorgio is a Counselor &#8211; Mental Health based out of Boulder, Colorado and her medical specialization is Counselor &#8211; Mental Health. She practices in Boulder, Colorado and has the professional credentials of MA, LPC. The NPI Number for Ms. Maria Grazia Di Giorgio is 1922252402 and she holds a Licence No. [&hellip;]","og_url":"https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/","og_site_name":"JungianDirectory","article_modified_time":"2026-01-03T20:33:13+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/","url":"https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/","name":"Maria Grazia Di Giorgio - JungianDirectory","isPartOf":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#website"},"datePublished":"2026-01-02T07:28:03+00:00","dateModified":"2026-01-03T20:33:13+00:00","breadcrumb":{"@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/maria-grazia-di-giorgio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jungian.directory\/fcxfougk\/"},{"@type":"ListItem","position":2,"name":"Analysts","item":"https:\/\/jungian.directory\/fcxfougk\/analyst\/"},{"@type":"ListItem","position":3,"name":"Maria Grazia Di Giorgio"}]},{"@type":"WebSite","@id":"https:\/\/jungian.directory\/fcxfougk\/#website","url":"https:\/\/jungian.directory\/fcxfougk\/","name":"JungianDirectory","description":"Analysts, Events, Training, CPD, Books, etc","publisher":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jungian.directory\/fcxfougk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/jungian.directory\/fcxfougk\/#organization","name":"JungianDirectory","url":"https:\/\/jungian.directory\/fcxfougk\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/jungian.directory\/fcxfougk\/#\/schema\/logo\/image\/","url":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2024\/02\/cropped-new-logo-test-2024-03-03.png","contentUrl":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2024\/02\/cropped-new-logo-test-2024-03-03.png","width":512,"height":512,"caption":"JungianDirectory"},"image":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst\/14914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst"}],"about":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/types\/analyst"}],"author":[{"embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst\/14914\/revisions"}],"wp:attachment":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/media?parent=14914"}],"wp:term":[{"taxonomy":"iaap-status","embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/iaap-status?post=14914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}