{"id":16098,"date":"2026-01-02T07:53:44","date_gmt":"2026-01-02T07:53:44","guid":{"rendered":"https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gadar-gardarsson\/"},"modified":"2026-01-03T20:34:02","modified_gmt":"2026-01-03T20:34:02","slug":"helgi-gardar-gardarsson","status":"publish","type":"analyst","link":"https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gardar-gardarsson\/","title":{"rendered":"Helgi Gar\u00f0ar Gar\u00f0arsson"},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","iaap-status":[],"class_list":["post-16098","analyst","type-analyst","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Helgi Gar\u00f0ar Gar\u00f0arsson - JungianDirectory<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Helgi Gar\u00f0ar Gar\u00f0arsson\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gardar-gardarsson\/\" \/>\n<meta property=\"og:site_name\" content=\"JungianDirectory\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-03T20:34:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/helgi-gardar-gardarsson\\\/\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/helgi-gardar-gardarsson\\\/\",\"name\":\"Helgi Gar\u00f0ar Gar\u00f0arsson - JungianDirectory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#website\"},\"datePublished\":\"2026-01-02T07:53:44+00:00\",\"dateModified\":\"2026-01-03T20:34:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/helgi-gardar-gardarsson\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/helgi-gardar-gardarsson\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/helgi-gardar-gardarsson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analysts\",\"item\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/analyst\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Helgi Gar\u00f0ar Gar\u00f0arsson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#website\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\",\"name\":\"JungianDirectory\",\"description\":\"Analysts, Events, Training, CPD, Books, etc\",\"publisher\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#organization\",\"name\":\"JungianDirectory\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-new-logo-test-2024-03-03.png\",\"contentUrl\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-new-logo-test-2024-03-03.png\",\"width\":512,\"height\":512,\"caption\":\"JungianDirectory\"},\"image\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Helgi Gar\u00f0ar Gar\u00f0arsson - JungianDirectory","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Helgi Gar\u00f0ar Gar\u00f0arsson","og_url":"https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gardar-gardarsson\/","og_site_name":"JungianDirectory","article_modified_time":"2026-01-03T20:34:02+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gardar-gardarsson\/","url":"https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gardar-gardarsson\/","name":"Helgi Gar\u00f0ar Gar\u00f0arsson - JungianDirectory","isPartOf":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#website"},"datePublished":"2026-01-02T07:53:44+00:00","dateModified":"2026-01-03T20:34:02+00:00","breadcrumb":{"@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gardar-gardarsson\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gardar-gardarsson\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jungian.directory\/fcxfougk\/analyst\/helgi-gardar-gardarsson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jungian.directory\/fcxfougk\/"},{"@type":"ListItem","position":2,"name":"Analysts","item":"https:\/\/jungian.directory\/fcxfougk\/analyst\/"},{"@type":"ListItem","position":3,"name":"Helgi Gar\u00f0ar Gar\u00f0arsson"}]},{"@type":"WebSite","@id":"https:\/\/jungian.directory\/fcxfougk\/#website","url":"https:\/\/jungian.directory\/fcxfougk\/","name":"JungianDirectory","description":"Analysts, Events, Training, CPD, Books, etc","publisher":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jungian.directory\/fcxfougk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/jungian.directory\/fcxfougk\/#organization","name":"JungianDirectory","url":"https:\/\/jungian.directory\/fcxfougk\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/jungian.directory\/fcxfougk\/#\/schema\/logo\/image\/","url":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2024\/02\/cropped-new-logo-test-2024-03-03.png","contentUrl":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2024\/02\/cropped-new-logo-test-2024-03-03.png","width":512,"height":512,"caption":"JungianDirectory"},"image":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst\/16098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst"}],"about":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/types\/analyst"}],"author":[{"embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/analyst\/16098\/revisions"}],"wp:attachment":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/media?parent=16098"}],"wp:term":[{"taxonomy":"iaap-status","embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/iaap-status?post=16098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}