{"id":1893,"date":"2020-11-29T09:31:16","date_gmt":"2020-11-29T09:31:16","guid":{"rendered":"https:\/\/jungian.directory\/fcxfougk\/?post_type=related_organisation&#038;p=1893"},"modified":"2021-08-22T22:01:40","modified_gmt":"2021-08-22T21:01:40","slug":"the-c-g-jung-society-of-saint-louis","status":"publish","type":"related_organisation","link":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/","title":{"rendered":"The C.G. Jung Society of Saint Louis"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":23124,"parent":0,"template":"","organisation_type":[145],"class_list":["post-1893","related_organisation","type-related_organisation","status-publish","has-post-thumbnail","hentry","organisation_type-club-or-society"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The C.G. Jung Society of Saint Louis - JungianDirectory<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The C.G. Jung Society of Saint Louis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/\" \/>\n<meta property=\"og:site_name\" content=\"JungianDirectory\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-22T21:01:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2020\/11\/551436_531216100243085_1518710316_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/the-c-g-jung-society-of-saint-louis\\\/\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/the-c-g-jung-society-of-saint-louis\\\/\",\"name\":\"The C.G. Jung Society of Saint Louis - JungianDirectory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/the-c-g-jung-society-of-saint-louis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/the-c-g-jung-society-of-saint-louis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/551436_531216100243085_1518710316_n.jpg\",\"datePublished\":\"2020-11-29T09:31:16+00:00\",\"dateModified\":\"2021-08-22T21:01:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/the-c-g-jung-society-of-saint-louis\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/the-c-g-jung-society-of-saint-louis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/the-c-g-jung-society-of-saint-louis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/551436_531216100243085_1518710316_n.jpg\",\"contentUrl\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/551436_531216100243085_1518710316_n.jpg\",\"width\":350,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/the-c-g-jung-society-of-saint-louis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Related Organisations\",\"item\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/related_organisation\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The C.G. Jung Society of Saint Louis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#website\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\",\"name\":\"JungianDirectory\",\"description\":\"Analysts, Events, Training, CPD, Books, etc\",\"publisher\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#organization\",\"name\":\"JungianDirectory\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-new-logo-test-2024-03-03.png\",\"contentUrl\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-new-logo-test-2024-03-03.png\",\"width\":512,\"height\":512,\"caption\":\"JungianDirectory\"},\"image\":{\"@id\":\"https:\\\/\\\/jungian.directory\\\/fcxfougk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The C.G. Jung Society of Saint Louis - JungianDirectory","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"The C.G. Jung Society of Saint Louis","og_url":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/","og_site_name":"JungianDirectory","article_modified_time":"2021-08-22T21:01:40+00:00","og_image":[{"width":350,"height":350,"url":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2020\/11\/551436_531216100243085_1518710316_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/","url":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/","name":"The C.G. Jung Society of Saint Louis - JungianDirectory","isPartOf":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/#primaryimage"},"image":{"@id":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/#primaryimage"},"thumbnailUrl":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2020\/11\/551436_531216100243085_1518710316_n.jpg","datePublished":"2020-11-29T09:31:16+00:00","dateModified":"2021-08-22T21:01:40+00:00","breadcrumb":{"@id":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/#primaryimage","url":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2020\/11\/551436_531216100243085_1518710316_n.jpg","contentUrl":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2020\/11\/551436_531216100243085_1518710316_n.jpg","width":350,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/the-c-g-jung-society-of-saint-louis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jungian.directory\/fcxfougk\/"},{"@type":"ListItem","position":2,"name":"Related Organisations","item":"https:\/\/jungian.directory\/fcxfougk\/related_organisation\/"},{"@type":"ListItem","position":3,"name":"The C.G. Jung Society of Saint Louis"}]},{"@type":"WebSite","@id":"https:\/\/jungian.directory\/fcxfougk\/#website","url":"https:\/\/jungian.directory\/fcxfougk\/","name":"JungianDirectory","description":"Analysts, Events, Training, CPD, Books, etc","publisher":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jungian.directory\/fcxfougk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/jungian.directory\/fcxfougk\/#organization","name":"JungianDirectory","url":"https:\/\/jungian.directory\/fcxfougk\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/jungian.directory\/fcxfougk\/#\/schema\/logo\/image\/","url":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2024\/02\/cropped-new-logo-test-2024-03-03.png","contentUrl":"https:\/\/jungian.directory\/fcxfougk\/wp-content\/uploads\/2024\/02\/cropped-new-logo-test-2024-03-03.png","width":512,"height":512,"caption":"JungianDirectory"},"image":{"@id":"https:\/\/jungian.directory\/fcxfougk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/related_organisation\/1893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/related_organisation"}],"about":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/types\/related_organisation"}],"author":[{"embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/related_organisation\/1893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/media\/23124"}],"wp:attachment":[{"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/media?parent=1893"}],"wp:term":[{"taxonomy":"organisation_type","embeddable":true,"href":"https:\/\/jungian.directory\/fcxfougk\/wp-json\/wp\/v2\/organisation_type?post=1893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}